{"id":400,"date":"2024-01-16T14:28:04","date_gmt":"2024-01-16T13:28:04","guid":{"rendered":"https:\/\/stucchi.9bureaudigitalagency.it\/?page_id=400"},"modified":"2024-11-27T14:48:51","modified_gmt":"2024-11-27T13:48:51","slug":"lighting-components","status":"publish","type":"page","link":"https:\/\/staging.aagstucchi.it\/en\/lighting-components\/","title":{"rendered":"Lighting Components"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/elenco-componenti-illuminazione.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-400","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lighting Components - Stucchi Inglese<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lighting Components - Stucchi Inglese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stucchi.9bureaudigitalagency.it\/en\/lighting-components\/\" \/>\n<meta property=\"og:site_name\" content=\"Stucchi Inglese\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T13:48:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/lighting-components\\\/\",\"url\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/lighting-components\\\/\",\"name\":\"Lighting Components - Stucchi Inglese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/#website\"},\"datePublished\":\"2024-01-16T13:28:04+00:00\",\"dateModified\":\"2024-11-27T13:48:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/lighting-components\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/lighting-components\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/lighting-components\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lighting Components\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/\",\"name\":\"Stucchi Inglese\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stucchi.9bureaudigitalagency.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lighting Components - Stucchi Inglese","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Lighting Components - Stucchi Inglese","og_url":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/lighting-components\/","og_site_name":"Stucchi Inglese","article_modified_time":"2024-11-27T13:48:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/lighting-components\/","url":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/lighting-components\/","name":"Lighting Components - Stucchi Inglese","isPartOf":{"@id":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/#website"},"datePublished":"2024-01-16T13:28:04+00:00","dateModified":"2024-11-27T13:48:51+00:00","breadcrumb":{"@id":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/lighting-components\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stucchi.9bureaudigitalagency.it\/en\/lighting-components\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/lighting-components\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/"},{"@type":"ListItem","position":2,"name":"Lighting Components"}]},{"@type":"WebSite","@id":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/#website","url":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/","name":"Stucchi Inglese","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stucchi.9bureaudigitalagency.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/pages\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/comments?post=400"}],"version-history":[{"count":3,"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/pages\/400\/revisions"}],"predecessor-version":[{"id":1097,"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/pages\/400\/revisions\/1097"}],"wp:attachment":[{"href":"https:\/\/staging.aagstucchi.it\/en\/wp-json\/wp\/v2\/media?parent=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}